{"id":14966,"date":"2021-05-29T16:51:18","date_gmt":"2021-05-29T14:51:18","guid":{"rendered":"https:\/\/cine-techno.com\/wp\/?p=14966"},"modified":"2021-06-06T19:56:16","modified_gmt":"2021-06-06T17:56:16","slug":"concours-spirit-untamed-spirit-lindomptable-voyez-le-film-au-cinema","status":"publish","type":"post","link":"https:\/\/cine-techno.com\/wp\/2021\/05\/29\/concours-spirit-untamed-spirit-lindomptable-voyez-le-film-au-cinema\/","title":{"rendered":"Termin\u00e9 &#8211; [Concours] &#8211; Spirit Untamed (Spirit: L&rsquo;indomptable), voyez le film au cin\u00e9ma"},"content":{"rendered":"<p>F\u00e9licitation aux personnes gagnantes :<\/p>\n<p>Fanja Rajesson<br \/>\nMarie-Chantal Lord<\/p>\n<p><a href=\"http:\/\/www.universalpictures.ca\" target=\"_blank\" rel=\"noopener\"><strong>Universal Pictures Canada<\/strong><\/a> offre la chance de gagner un des deux (2) laissez-passer doubles pour aller voir au cin\u00e9ma le film <a href=\"https:\/\/www.dreamworks.com\/movies\/spirit-untamed\" target=\"_blank\" rel=\"noopener\">Spirit Untamed (Spirit: L&rsquo;indomptable)<\/a> (en fran\u00e7ais ou en anglais d\u00e8s le 4 juin 2021) pour nos participants dans le cadre de notre concours.<\/p>\n<p>[sc name=\u00a0\u00bbpub_google_720_90&Prime;]<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14968\" src=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2021\/05\/Spirit-Untamed-poster-450.jpg\" alt=\"\" width=\"324\" height=\"480\" srcset=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2021\/05\/Spirit-Untamed-poster-450.jpg 450w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2021\/05\/Spirit-Untamed-poster-450-203x300.jpg 203w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14967\" src=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2021\/05\/Spirit-Untamed-FR-affiche-450.jpg\" alt=\"\" width=\"323\" height=\"476\" srcset=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2021\/05\/Spirit-Untamed-FR-affiche-450.jpg 450w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2021\/05\/Spirit-Untamed-FR-affiche-450-203x300.jpg 203w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/p>\n<p style=\"font-weight: 400;\">C\u2019est l\u2019aventure \u00e9pique d\u2019une fille un peu rebelle, en qu\u00eate d\u2019un endroit qui lui ressemble. Elle rencontre son \u00e2me s\u0153ur qui n\u2019est autre qu\u2019un cheval sauvage. Spirit: L\u2019indomptable est le nouveau chapitre de la fameuse histoire de DreamWorks Animation.<\/p>\n<p style=\"font-weight: 400;\">Lucky Prescott (Isabela Merced, Dora et la Cit\u00e9 d\u2019or perdue) n\u2019a jamais vraiment connu sa d\u00e9funte m\u00e8re, Milagro Navarro (Eiza Gonz\u00e1lez, Rapides et dangereux pr\u00e9sentent : Hobbs et Shaw), une cavali\u00e8re et cascadeuse t\u00e9m\u00e9raire de Miradero, petite ville frontali\u00e8re ouverte sur l\u2019infini.<\/p>\n<p style=\"font-weight: 400;\">\u00c0 l\u2019image de sa m\u00e8re, Lucky n\u2019appr\u00e9cie pas particuli\u00e8rement les r\u00e8glement et les interdits, ce qui inqui\u00e8te beaucoup sa tante Cora (Julianne Moore, laur\u00e9ate aux Academy AwardMD). Lucky a grandi dans une ville de la c\u00f4te Est, sous la responsabilit\u00e9 de Cora. Suite aux nombreuses fugues de Lucky, sa tante d\u00e9cide de d\u00e9m\u00e9nager avec sa ni\u00e8ce chez Jim (Jake Gyllenhaal nomm\u00e9 aux OscarsMD) le p\u00e8re de cette derni\u00e8re, \u00e9tabli \u00e0 Miradero.<\/p>\n<p style=\"font-weight: 400;\">Lucky n\u2019appr\u00e9cie pas vraiment cette petite ville trop tranquille. Mais elle vit un v\u00e9ritable coup de foudre lorsqu\u2019elle rencontre Spirit, un mustang sauvage qui semble partager la m\u00eame soif d\u2019ind\u00e9pendance et elle devient amie avec deux cavali\u00e8res de la r\u00e9gion, Abigail Stone (Mckenna Grace, Capitaine Marvel) et Pru Granger (Marsai Martin, Petite). Le p\u00e8re de Pru, Al Granger propri\u00e9taire d\u2019une \u00e9curie (Andre Braugher laur\u00e9at aux Emmy et vu dans Brooklyn Nine-Nine de Fox) est le meilleur ami du p\u00e8re de Lucky.<\/p>\n<p style=\"font-weight: 400;\">Lorsqu\u2019un trafiquant de chevaux sans c\u0153ur (Walton Goggins, nomm\u00e9 aux Emmy et vu dans Justifi\u00e9 de FX) et ses acolytes projettent de voler Spirit et son troupeau pour les vendre aux ench\u00e8res, Lucky embarque ses amies dans ou courageuse aventure. Elle d\u00e9cide de porter secours et de sauver le cheval qui lui a rendu sa libert\u00e9 et sa raison d\u2019\u00eatre et qui lui a permis de red\u00e9couvrir l\u2019h\u00e9ritage de sa m\u00e8re et ses origines mexicaines qu\u2019elle ignorait.<\/p>\n<p style=\"font-weight: 400;\">Spirit: L\u2019indomptable est le nouveau chapitre de la fameuse franchise de DreamWorks Animation qui avait d\u00e9but\u00e9 en 2002 avec le film nomm\u00e9 aux Oscars Spirit: l\u2019\u00e9talon des plaines qui a aussi fait l\u2019objet d\u2019une s\u00e9rie TV laur\u00e9ate aux Emmy. Le film est r\u00e9alis\u00e9 par Elaine Bogan (Chasseurs de Trolls : Les Contes d\u2019Arcadia de Netflix et DreamWorks Animation Television) et est produit par Karen Foster (coproductrice de Dragons). Le cor\u00e9alisateur du film est Ennio Torresan (sc\u00e9nariste, Le B\u00e9b\u00e9 Boss), la bande sonore du film a \u00e9t\u00e9 compos\u00e9e par Amie Doherty (Undone d\u2019Amazone, Abominable de DreamWorks Animation).<\/p>\n<p style=\"font-weight: 400;\"><strong>Distribution<\/strong><\/p>\n<p style=\"font-weight: 400;\">Isabela Merced<br \/>\nJulianne Moore<br \/>\nJake Gyllenhaal<br \/>\nMarsai Martin<br \/>\nMckenna Grace<br \/>\nWalton Goggins<br \/>\nAndre Braugher<br \/>\nEiza Gonz\u00e1lez<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>R\u00e9alisatrice<\/strong><\/p>\n<p style=\"font-weight: 400;\">Elaine Bogan<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>\u00c9crit par<\/strong><\/p>\n<p style=\"font-weight: 400;\">Karen Foster<\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong><strong>Productrice<\/strong><\/p>\n<p style=\"font-weight: 400;\">Karen Foster<\/p>\n<p><iframe loading=\"lazy\" title=\"Spirit: L\u2019indomptable | Bande-annonce officielle\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/ZBMO1aWXpdw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p><iframe loading=\"lazy\" title=\"Spirit Untamed - Trailer\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/m-PQ1gWrI7E?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Bonne chance!<\/p>\n<p>Compl\u00e9tez le formulaire suivant :<\/p>\n<p>&nbsp;<\/p>\n<p>[sc name=\u00a0\u00bbpub_google_720_90&Prime;]<\/p>\n<p>R\u00e8glements<\/p>\n<ul>\n<li>Le concours se termine le <strong>2021-06-02 <\/strong>\u00e0 minuit (heure du Qu\u00e9bec)<\/li>\n<li>Une seule participation par personne est admise.<\/li>\n<li>Seuls les r\u00e9sidents du Qu\u00e9bec peuvent participer au concours.<\/li>\n<li>Les personnes suivantes ne peuvent participer au concours : les collaborateurs \u00e0 cine-techno.com ainsi que leurs familles et les partenaires de cine-techno.com<\/li>\n<li>Le(s) nom(s) du ou des gagnants seront affich\u00e9(s) sur le site de cine-techno.com<\/li>\n<li>Le(s) gagnant(s) seront avis\u00e9(s) par courriel.<\/li>\n<li>\u00c0 l&rsquo;occasion, votre adresse courriel peut \u00eatre utilis\u00e9 par cine-techno.com afin de faire de la promotion.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>F\u00e9licitation aux personnes gagnantes : Fanja Rajesson Marie-Chantal Lord Universal Pictures Canada offre la chance&#8230;<\/p>\n","protected":false},"author":1,"featured_media":14969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[2,55,3810],"tags":[169,6065,93,59,6063,6064],"class_list":["post-14966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema","category-concours","category-film","tag-animation","tag-cheval","tag-cinema","tag-concours","tag-spirit-untamed","tag-spirit-lindomptable"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/14966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/comments?post=14966"}],"version-history":[{"count":2,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/14966\/revisions"}],"predecessor-version":[{"id":15127,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/14966\/revisions\/15127"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/media\/14969"}],"wp:attachment":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/media?parent=14966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/categories?post=14966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/tags?post=14966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}