{"id":28376,"date":"2023-08-31T17:47:28","date_gmt":"2023-08-31T15:47:28","guid":{"rendered":"https:\/\/cine-techno.com\/wp\/?p=28376"},"modified":"2023-08-31T18:49:23","modified_gmt":"2023-08-31T16:49:23","slug":"autez-dans-linconnu-avec-la-presentation-du-jeu-super-mario-bros-wonder","status":"publish","type":"post","link":"https:\/\/cine-techno.com\/wp\/2023\/08\/31\/autez-dans-linconnu-avec-la-presentation-du-jeu-super-mario-bros-wonder\/","title":{"rendered":"Sautez dans l\u2019inconnu avec la pr\u00e9sentation du jeu Super Mario Bros. Wonder"},"content":{"rendered":"<p><b>VANCOUVER, B.C., 31 ao\u00fbt 2023 \u2013\u00a0<\/b>Lors de la pr\u00e9sentation vid\u00e9o\u00a0<a id=\"m_6765454267904486874OWA365c8a36-79ab-1105-81d5-1989b255354f\" href=\"https:\/\/www.nintendo.com\/fr-ca\/store\/products\/super-mario-bros-wonder-switch\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr-ca\/store\/products\/super-mario-bros-wonder-switch\/&amp;source=gmail&amp;ust=1693581901214000&amp;usg=AOvVaw0R1d4BoIkehpCr9S3y5Ctw\"><i>Super Mario Bros. Wonder<\/i><\/a>\u00a0Direct, Nintendo a montr\u00e9\u00a0pr\u00e8s de\u00a015 minutes de s\u00e9quences de jeu\u00a0surprenantes, de nouveaux pouvoirs et des effets transformatifs prodigieux dans ce prochain jeu Nintendo Switch offert d\u00e8s le 20 octobre prochain. Pour regarder la pr\u00e9sentation compl\u00e8te Nintendo Direct sur\u00a0<i>Super Mario Bros. Wonder<\/i>, visitez la\u00a0<a id=\"m_6765454267904486874OWA4a8910fe-66d4-22d7-b595-6f7fb8a081a7\" href=\"https:\/\/www.youtube.com\/c\/nintendo\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.youtube.com\/c\/nintendo&amp;source=gmail&amp;ust=1693581901214000&amp;usg=AOvVaw2Rg2z-JrVd5K3zPKByEg-_\">cha\u00eene YouTube de Nintendo<\/a>.<\/p>\n<p>[sc name=\u00a0\u00bbpub_google_720_90&Prime;]<\/p>\n<p><iframe loading=\"lazy\" title=\"Super Mario Bros. Wonder Direct 8.31.2023\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/G0m_uNaSres?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Pr\u00e9parez-vous \u00e0 sauter dans l\u2019inconnu avec le jeu\u00a0<i>Super Mario Bros. Wonder\u00a0<\/i>\u2013 la prochaine \u00e9volution\u00a0\u00e9tonnante de la franchise\u00a0et le premier jeu Super Mario Bros. \u00e0 d\u00e9filement horizontal en 2D depuis plus de 10 ans! Avec un nouveau royaume des Fleurs \u00e0 explorer et une distribution vari\u00e9e de personnages jouables, le jeu\u00a0<i>Super Mario Bros. Wonder<\/i>\u00a0introduit aussi les fleurs prodiges, des objets r\u00e9volutionnaires du jeu qui cr\u00e9ent d\u2019incroyables et surprenants\u00a0effets.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-28378\" src=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2023\/08\/Nintendo-Switch-Modele-OLED-Edition-Mario-rouge.png\" alt=\"\" width=\"347\" height=\"429\" srcset=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2023\/08\/Nintendo-Switch-Modele-OLED-Edition-Mario-rouge.png 1524w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2023\/08\/Nintendo-Switch-Modele-OLED-Edition-Mario-rouge-243x300.png 243w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2023\/08\/Nintendo-Switch-Modele-OLED-Edition-Mario-rouge-829x1024.png 829w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2023\/08\/Nintendo-Switch-Modele-OLED-Edition-Mario-rouge-768x949.png 768w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2023\/08\/Nintendo-Switch-Modele-OLED-Edition-Mario-rouge-1243x1536.png 1243w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2023\/08\/Nintendo-Switch-Modele-OLED-Edition-Mario-rouge-1024x1265.png 1024w\" sizes=\"auto, (max-width: 347px) 100vw, 347px\" \/><\/p>\n<p>Juste \u00e0 temps pour cette\u00a0nouvelle aventure de Mario, une console Nintendo Switch &#8211; Mod\u00e8le OLED : \u00c9dition Mario rouge sera offerte en magasins le 6 octobre prochain, au prix de d\u00e9tail sugg\u00e9r\u00e9 de 449,99 $. La console*, ainsi que ses deux manettes Joy-Con et la station d\u2019accueil Nintendo Switch\u00a0arborera\u00a0la couleur rouge iconique de Mario.\u00a0Une\u00a0silhouette de Mario\u00a0agr\u00e9mente\u00a0l\u2019arri\u00e8re de\u00a0la station d\u2019accueil. Regardez de plus pr\u00e8s et vous trouverez \u00e9galement\u00a0quelques\u00a0pi\u00e8ces! Visitez\u00a0vos\u00a0d\u00e9taillants locaux pour\u00a0plus d\u2019informations sur les\u00a0pr\u00e9commandes bient\u00f4t. Pour plus d\u2019informations sur la console\u00a0:\u00a0<a id=\"m_6765454267904486874OWA34a8081e-3256-c816-bc6b-429250663db5\" href=\"https:\/\/www.nintendo.com\/fr-ca\/retail-offers\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr-ca\/retail-offers\/&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw1fJ8hiVioRAq_5YXIx3Nb3\">https:\/\/www.nintendo.com\/fr-<wbr \/>ca\/retail-offers\/<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>Dans le jeu\u00a0<i>Super Mario Bros. Wonder<\/i>, le bienveillant Prince Florian invite Mario et ses amis dans le royaume des Fleurs, une contr\u00e9e proche du royaume Champignon. Mais Bowser, le roi des Koopas, a d\u2019autres plans. En touchant simplement la myst\u00e9rieuse fleur prodige, Bowser fusionne avec le ch\u00e2teau du Prince Florian. Gr\u00e2ce \u00e0 son tout nouveau pouvoir, le chaos s\u2019installe dans la contr\u00e9e. C\u2019est maintenant \u00e0 Mario et ses amis d\u2019arr\u00eater Bowser et de sauver le royaume des Fleurs! Voici quelques caract\u00e9ristiques et un aper\u00e7u de ce que les joueurs rencontreront lors de cette aventure florale\u00a0:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>Un royaume grouillant de vari\u00e9t\u00e9s :<\/b>\u00a0Le royaume des Fleurs est compos\u00e9 de six mondes distincts qui entourent les \u00eeles florales, vous offrant ainsi un total de sept zones \u00e0 explorer. Traversez plusieurs \u00eeles, plongez dans la mer et pratiquez la sp\u00e9l\u00e9ologie dans les grottes. Une riche vari\u00e9t\u00e9 de niveaux vous attend dans chaque monde, et vous pouvez m\u00eame vous d\u00e9placer librement \u00e0 travers des zones ouvertes de la carte du monde!<\/li>\n<li><b>Curieux \u00e0 propos des effets prodiges?<\/b>\u00a0Attendez-vous \u00e0 l\u2019inattendu : Les fleurs prodiges prosp\u00e8rent gr\u00e2ce au myst\u00e9rieux pouvoir de ce monde et le lib\u00e8rent une fois \u00e9closes. Lorsque vous touchez une fleur prodige dans un niveau, un effet prodige se produit, causant des changements dramatiques. Des tuyaux peuvent commencer \u00e0 bouger, le sol peut s\u2019incliner, votre perspective peut changer ou vous pouvez flotter dans l\u2019espace! Il existe m\u00eame des prodiges qui peuvent transformer votre personnage en un Goomba ou une Boule Spikante.<b>\u00a0<\/b><\/li>\n<li><b>Personnages charismatiques \u00e0 vos ordres :\u00a0<\/b>En plus de Mario, vous pouvez aussi jouer le r\u00f4le de<b>\u00a0<\/b>Luigi, Peach, Daisy, Toad bleu, Toad jaune et m\u00eame Toadette. Ils sont tous jouables de la m\u00eame fa\u00e7on, alors utilisez votre personnage favori ou un personnage diff\u00e9rent. Les Yoshis et Chipin ne subissent pas de d\u00e9g\u00e2ts, ils sont donc le choix id\u00e9al si vous \u00eates \u00e0 la recherche d\u2019une exp\u00e9rience plus facile.<\/li>\n<li><b>Plusieurs transformations\u00a0<\/b>: Le jeu\u00a0<i>Super Mario Bros. Wonder<\/i>\u00a0comprend les d\u00e9buts de nouvelles transformations comme Pomme d\u2019\u00e9l\u00e9phant, qui permet \u00e0 Mario et certains de ses amis de se transformer en \u00c9l\u00e9phant! Utilisez votre poids et votre trompe pour attaquer les ennemis, d\u00e9truire des blocs et foncer \u00e0 travers de larges ouvertures. La forme Bulles permet de souffler des bulles flottantes qui peuvent \u00eatre utilis\u00e9es pour capturer des ennemis \u00e0 distance. La forme Foreuse facilite le combat contre les ennemis \u00e0 pics et \u00e0 t\u00eates dures. Elle permet aussi de creuser et de se d\u00e9placer dans le sol.<\/li>\n<li><b>Ne laissez pas vos ennemis vous avoir\u00a0<\/b>: Pour ce qu\u2019il s\u2019agit d\u2019ennemis, vous en rencontrerez des nouveaux qui sont peu fiables lors de vos balades dans le royaume des Fleurs. Les Bondiss vous imitent et sautent lorsque vous sautez. Les Melons d&rsquo;eau Piranha crachent des graines. Les Pikdors vous volent dessus et mettent leurs becs dans vos affaires. Les Salabafres mangent tout ce qui se rapproche de leurs bouches b\u00e9antes. Il y a beaucoup de nouveaux ennemis \u00e0 d\u00e9couvrir!<\/li>\n<li><b>Munissez-vous d\u2019un badge pour bouleverser les choses :\u00a0<\/b>Au fur et \u00e0 mesure de votre aventure, vous pourrez obtenir une vari\u00e9t\u00e9 de badges dans le jeu, chacun poss\u00e9dant sa propre caract\u00e9ristique sp\u00e9ciale. En mode multijoueur local, chaque groupe de joueurs utilisera le m\u00eame badge. D\u00e9couvrez quelques options\u00a0amusantes\u00a0disponibles :\n<ul>\n<li>Am\u00e9liorez vos comp\u00e9tences en saut mural avec le badge Saut d&rsquo;escalade.<\/li>\n<li>Munissez-vous du badge Coup du dauphin pour aller plus vite sous l\u2019eau.<\/li>\n<li>Utilisez le badge Grand saut accroupi pour effectuer un grand saut.<\/li>\n<li>Projetez des vignes en l\u2019air et accrochez-vous aux murs avec le badge Vigne grappin.<\/li>\n<li>Pour une arme \u00e0 double tranchant et un d\u00e9fi additionnel, devenez invisible pour vos ennemis (et vous-m\u00eame) avec le badge Invisibilit\u00e9.<\/li>\n<\/ul>\n<\/li>\n<li><b>Multipliez le plaisir avec le mode multijoueur local\u00a0<\/b>: Jusqu\u2019\u00e0 quatre joueurs peuvent jouer localement sur la m\u00eame console Nintendo Switch. Si un joueur est vaincu en mode coop\u00e9ratif local**, son personnage flottera dans le niveau en tant que fant\u00f4me. Si un autre joueur le touche avant la fin du temps imparti, il reviendra dans l\u2019action, et le groupe ne perdra aucune vie. Si un joueur joue en tant que Yoshi, vous pouvez monter sur son dos et le chevaucher tout au long du niveau. Allez, hue!<\/li>\n<li><b>Embarquez dans le jeu en ligne\u00a0<\/b>: En jouant en ligne***, vous avez l\u2019option de cr\u00e9er une session entre amis lors de laquelle vous pouvez voir \u00e0 quels niveaux vos amis jouent, jouer au m\u00eame niveau ensemble et m\u00eame transformer la plupart des niveaux en une course amicale. M\u00eame en jouant en solo, si vous vous connectez en ligne, vous pouvez voir les autres joueurs \u00e0 travers le monde dans des niveaux ou sur la carte du monde en temps r\u00e9el sous la forme d\u2019ombres de joueurs. Vous pouvez aussi revenir \u00e0 la vie en percutant l\u2019ombre d\u2019un joueur! De plus, vous pouvez aider les autres joueurs en ligne en pla\u00e7ant un panneau qu\u2019ils peuvent utiliser pour r\u00e9animer des fant\u00f4mes. Placez-les intelligemment dans des endroits difficiles pour (vraiment) aider un joueur. Le jeu affichera m\u00eame le nombre de joueurs qui ont utilis\u00e9 votre panneau!\n<div><\/div>\n<p><i>Super Mario Bros. Wonder<\/i>\u00a0sera disponible\u00a0chez certains d\u00e9taillants, dans le Nintendo eShop sur Nintendo Switch et dans la\u00a0<a id=\"m_6765454267904486874OWA599a2b1c-1086-de65-727b-9cb71e70b469\" href=\"https:\/\/www.nintendo.com\/fr-ca\/store\/products\/super-mario-bros-wonder-switch\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr-ca\/store\/products\/super-mario-bros-wonder-switch\/&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw1CURPrapZUR-uhiJ8MBaWO\">boutique My Nintendo<\/a>\u00a0d\u00e8s le 20 octobre prochain, au prix de d\u00e9tail sugg\u00e9r\u00e9 de 79,99 $. Pour les joueurs qui sont pr\u00eats \u00e0 sauter dans le royaume des Fleurs d\u00e8s la sortie du jeu, les pr\u00e9commandes sont\u00a0pr\u00e9sentement\u00a0offertes!<\/p>\n<div>Les abonn\u00e9s Nintendo Switch Online sont admissibles pour acheter les\u00a0<a id=\"m_6765454267904486874OWAdd4abc3e-80bd-011d-d6f0-d902964919b7\" href=\"https:\/\/www.nintendo.com\/fr-ca\/store\/products\/nintendo-switch-game-vouchers\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr-ca\/store\/products\/nintendo-switch-game-vouchers\/&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw3rE_Rm7bkEOX9-jzn-Xjl0\">Bons pour jeux Nintendo Switch****.<\/a>\u00a0Acheter une paire de bons pour jeux \u00e0 seulement 132,99 $ vous permet d\u2019\u00e9changer chaque bon contre un jeu num\u00e9rique dans le catalogue de jeux admissibles, y compris des titres premium comme\u00a0<i>Super Mario Bros. Wonder<\/i>. Pour plus de d\u00e9tails sur les bons pour jeux Nintendo Switch et pour consulter une liste de titres admissibles,\u00a0visitez\u00a0<a id=\"m_6765454267904486874OWAe93cf5c0-efa8-f675-e56c-6494ad13eaf1\" href=\"https:\/\/www.nintendo.com\/fr-ca\/store\/products\/nintendo-switch-game-vouchers\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr-ca\/store\/products\/nintendo-switch-game-vouchers\/&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw3rE_Rm7bkEOX9-jzn-Xjl0\">https:\/\/www.nintendo.<wbr \/>com\/fr-ca\/store\/products\/<wbr \/>nintendo-switch-game-vouchers\/<\/a><wbr \/>.<\/div>\n<div>Pour plus d\u2019informations \u00e0 propos du jeu\u00a0<i>Super Mario Bros. Wonder<\/i>, visitez\u00a0<a id=\"m_6765454267904486874OWA4d004445-f656-1fa7-3b46-c559a458107b\" href=\"https:\/\/www.nintendo.com\/fr-ca\/store\/products\/super-mario-bros-wonder-switch\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr-ca\/store\/products\/super-mario-bros-wonder-switch\/&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw1CURPrapZUR-uhiJ8MBaWO\">https:\/\/www.nintendo.<wbr \/>com\/fr-ca\/store\/products\/<wbr \/>super-mario-bros-wonder-<wbr \/>switch\/<\/a>.<\/div>\n<div><\/div>\n<p>La console Nintendo Switch offre une fonction de contr\u00f4le parental qui permet aux adultes de g\u00e9rer le contenu auquel leurs enfants peuvent acc\u00e9der. Pour plus d\u2019informations sur d\u2019autres fonctionnalit\u00e9s, visitez\u00a0<a id=\"m_6765454267904486874OWAa89fa1a3-c257-b9d8-1229-8d6ca3c8a0a0\" href=\"https:\/\/www.nintendo.com\/fr_CA\/switch\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr_CA\/switch\/&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw0awgymdOls415kmiT3R_Jp\">https:\/\/www.nintendo.com\/fr_<wbr \/>CA\/switch\/<\/a>.<\/p>\n<p>* Jeu non inclus<\/p>\n<p>** Des accessoires additionnels, vendus s\u00e9par\u00e9ment, pourraient \u00eatre n\u00e9cessaires pour le mode multijoueur.<br \/>\n*** Un abonnement Nintendo Switch Online (vendu s\u00e9par\u00e9ment) et un compte Nintendo sont n\u00e9cessaires pour utiliser les fonctions en ligne. L\u2019abonnement est renouvel\u00e9 automatiquement au prix en vigueur apr\u00e8s la p\u00e9riode de validit\u00e9 initiale, \u00e0 moins que le renouvellement automatique ne soit d\u00e9sactiv\u00e9. Pas offert dans tous les pays. Une connexion Internet est n\u00e9cessaire pour acc\u00e9der aux fonctions en ligne. Des termes s&rsquo;appliquent.\u00a0<a id=\"m_6765454267904486874OWA13a828ad-0bcb-44d6-525e-11f62423eb20\" href=\"https:\/\/www.nintendo.com\/fr_CA\/switch\/online-service\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.nintendo.com\/fr_CA\/switch\/online-service\/&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw2LaQ3-razHnrRR-3t7EPQe\">https:\/\/www.nintendo.com\/fr_<wbr \/>CA\/switch\/online-service\/<\/a><\/p>\n<p>**** Un abonnement payant au service Nintendo Switch Online est n\u00e9cessaire pour l&rsquo;achat et l&rsquo;\u00e9change de bons pour jeux Nintendo Switch. Les bons pour jeux Nintendo Switch doivent \u00eatre \u00e9chang\u00e9s dans les 12 mois suivant leur date d&rsquo;achat, n&rsquo;ont aucune valeur marchande, et ne peuvent pas \u00eatre transf\u00e9r\u00e9s, retourn\u00e9s, ou \u00e9chang\u00e9s contre de l&rsquo;argent. Chaque bon pour jeu Nintendo Switch peut \u00eatre \u00e9chang\u00e9 contre un jeu num\u00e9rique admissible. Pour profiter du rabais li\u00e9 \u00e0 ces bons, les bons pour jeux Nintendo Switch doivent \u00eatre \u00e9chang\u00e9s contre deux jeux avec un prix cumulatif qui est sup\u00e9rieur au prix d\u2019achat des bons pour jeux Nintendo Switch. Les bons pour jeux Nintendo Switch ne peuvent pas \u00eatre combin\u00e9s avec d&rsquo;autres offres, rabais ou offres promotionnelles, sauf indication contraire. Le catalogue de jeux pourrait changer.<\/p>\n<p><b>\u00c0 propos de Nintendo :<\/b>\u00a0Nintendo Co., Ltd., multinationale japonaise bas\u00e9e \u00e0 Kyoto au Japon, a cr\u00e9\u00e9 plusieurs franchises qui sont reconnues dans le monde entier telles que Mario, Donkey Kong, The Legend of Zelda, Metroid, Pok\u00e9mon, Animal Crossing, Pikmin et Splatoon, avec ses consoles int\u00e9gr\u00e9es et ses jeux. Nintendo cherche \u00e0 offrir des exp\u00e9riences de jeux uniques et intuitives pour tous, en fabriquant des consoles de jeux vid\u00e9o comme la famille de consoles Nintendo Switch, en d\u00e9veloppant et en op\u00e9rant des applications pour appareils intelligents et en collaborant avec une grande vari\u00e9t\u00e9 de partenaires dans plusieurs initiatives de divertissement comme du contenu visuel et des parcs d\u2019attractions. Nintendo a vendu plus de 5,6 milliards de jeux vid\u00e9o et plus de 800 millions de consoles \u00e0 l\u2019\u00e9chelle mondiale. Du lancement de la console Nintendo Entertainment System il y a plus de 30 ans \u00e0 aujourd\u2019hui et dans le futur, la mission de Nintendo est de cr\u00e9er un divertissement unique qui donne le sourire aux gens dans le monde entier. Nintendo of America est une filiale en propri\u00e9t\u00e9 exclusive bas\u00e9e \u00e0 Redmond, Washington, et \u0153uvre en qualit\u00e9 de si\u00e8ge social des op\u00e9rations de Nintendo dans les Am\u00e9riques. Pour plus d\u2019informations sur Nintendo, veuillez visiter le site de l\u2019entreprise\u00a0<a id=\"m_6765454267904486874OWA379fc251-1fdf-d0fd-603a-0a675a9b939f\" href=\"http:\/\/www.nintendo.com\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/www.nintendo.com&amp;source=gmail&amp;ust=1693581901215000&amp;usg=AOvVaw2BXomuncXZDuUOvxJHoyOE\">http:\/\/www.nintendo.com<\/a>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>VANCOUVER, B.C., 31 ao\u00fbt 2023 \u2013\u00a0Lors de la pr\u00e9sentation vid\u00e9o\u00a0Super Mario Bros. Wonder\u00a0Direct, Nintendo a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":28377,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[75,3805,33],"tags":[73,10405,10209],"class_list":["post-28376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jeux-video","category-nintendo-switch","category-nouvelle","tag-nintendo-switch","tag-nintendo-switch-modele-oled-edition-mario-rouge","tag-super-mario-bros-wonder"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/28376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/comments?post=28376"}],"version-history":[{"count":3,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/28376\/revisions"}],"predecessor-version":[{"id":30154,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/28376\/revisions\/30154"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/media\/28377"}],"wp:attachment":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/media?parent=28376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/categories?post=28376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/tags?post=28376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}