{"id":8011,"date":"2020-06-15T21:47:17","date_gmt":"2020-06-15T19:47:17","guid":{"rendered":"http:\/\/cine-techno.com\/wp\/?p=8011"},"modified":"2020-06-15T21:47:17","modified_gmt":"2020-06-15T19:47:17","slug":"critique-jeu-video-the-last-of-us-part-ii","status":"publish","type":"post","link":"https:\/\/cine-techno.com\/wp\/2020\/06\/15\/critique-jeu-video-the-last-of-us-part-ii\/","title":{"rendered":"[Critique jeu vid\u00e9o] The Last of Us Part II"},"content":{"rendered":"<p><a href=\"https:\/\/www.amazon.ca\/gp\/search?ie=UTF8&amp;keywords=The%20Last%20of%20Us&amp;tag=dvfron-20&amp;linkCode=ur2&amp;camp=15121&amp;creative=330641\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-8075\" src=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2020\/06\/The-Last-of-US-2-PS4-450.jpg\" alt=\"\" width=\"315\" height=\"408\" srcset=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2020\/06\/The-Last-of-US-2-PS4-450.jpg 450w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2020\/06\/The-Last-of-US-2-PS4-450-232x300.jpg 232w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.amazon.ca\/gp\/search?ie=UTF8&amp;keywords=The%20Last%20of%20Us&amp;tag=dvfron-20&amp;linkCode=ur2&amp;camp=15121&amp;creative=330641\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-100\" src=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2018\/07\/amazon_ca.gif\" alt=\"\" width=\"133\" height=\"36\" srcset=\"https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2018\/07\/amazon_ca.gif 133w, https:\/\/cine-techno.com\/wp\/wp-content\/uploads\/2018\/07\/amazon_ca-130x36.gif 130w\" sizes=\"auto, (max-width: 133px) 100vw, 133px\" \/><\/a><\/p>\n<p>Voici la critique du jeu <a href=\"https:\/\/www.amazon.ca\/gp\/search?ie=UTF8&amp;keywords=The%20Last%20of%20Us&amp;tag=dvfron-20&amp;linkCode=ur2&amp;camp=15121&amp;creative=330641\" target=\"_blank\" rel=\"noopener noreferrer\">The Last of Us Part II<\/a> d\u00e9velopp\u00e9 par <a href=\"https:\/\/www.naughtydog.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Naughty Dog<\/a>. Test\u00e9 et exclusivement disponible sur PS4.<\/p>\n<p>https:\/\/www.facebook.com\/cinetechno\/videos\/2687667938219814\/<\/p>\n<p>Cinq ans apr\u00e8s leur voyage p\u00e9rilleux \u00e0 travers une Am\u00e9rique ravag\u00e9e par une pand\u00e9mie, Ellie et Joel ont trouv\u00e9 refuge \u00e0 Jackson, dans le Wyoming chez Tommy, le fr\u00e8re de Joel. Vivre dans une communaut\u00e9 florissante de survivants leur a permis de conna\u00eetre la paix et la stabilit\u00e9 en d\u00e9pit de la menace constante des infect\u00e9s et des survivants d\u00e9sesp\u00e9r\u00e9s.<\/p>\n<p>Lorsqu&rsquo;un \u00e9v\u00e9nement violent trouble cette paix, Ellie se lance dans une qu\u00eate de justice pour enfin tourner la page. Alors qu&rsquo;elle pourchasse un \u00e0 un les responsables, elle doit affronter les r\u00e9percussions physiques et \u00e9motionnelles de ses actions.<\/p>\n<p>Aspects :<\/p>\n<p>Une histoire complexe remplie d&rsquo;\u00e9motion<\/p>\n<p>D\u00e9couvrez les conflits moraux croissants engendr\u00e9s par la qu\u00eate de vengeance implacable d&rsquo;Ellie. Le cycle de violence laiss\u00e9 sur son passage mettra \u00e0 l&rsquo;\u00e9preuve vos conceptions du bien et du mal, du h\u00e9ros contre le m\u00e9chant.<\/p>\n<p>Un monde magnifique, mais redoutable<\/p>\n<p>Embarquez pour l&rsquo;aventure d&rsquo;Ellie, qui vous m\u00e8nera loin des montagnes et for\u00eats paisibles de Jackson dans les ruines verdoyantes de Seattle. Rencontrez de nouveaux groupes de survivants, des environnements peu familiers et trompeurs et des versions \u00e9volu\u00e9es terrifiantes des infect\u00e9s.<\/p>\n<p>Gr\u00e2ce \u00e0 la nouvelle version du Naughty Dog engine, les personnages et paysages mortels sont plus r\u00e9alistes et plus d\u00e9taill\u00e9s que jamais.<\/p>\n<p>Un gameplay d&rsquo;action et de survie tendu et d\u00e9sesp\u00e9r\u00e9<\/p>\n<p>Des syst\u00e8mes de gameplay nouveaux et \u00e9volu\u00e9s livrent les enjeux de la qu\u00eate d&rsquo;Ellie \u00e0 travers ce monde hostile. Vivez son combat d\u00e9sesp\u00e9r\u00e9 \u00e0 travers des fonctionnalit\u00e9s am\u00e9lior\u00e9es comme des combats au corps \u00e0 corps intenses, des mouvements fluides et un syst\u00e8me de furtivit\u00e9 dynamique.<\/p>\n<p>Avec une grande vari\u00e9t\u00e9 d&rsquo;armes, d&rsquo;objet \u00e0 fabriquer, de comp\u00e9tences et d&rsquo;am\u00e9liorations, vous pourrez personnaliser les comp\u00e9tences d&rsquo;Ellie en fonction de votre style de jeu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici la critique du jeu The Last of Us Part II d\u00e9velopp\u00e9 par Naughty Dog&#8230;.<\/p>\n","protected":false},"author":6,"featured_media":8076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"cybocfi_hide_featured_image":"","footnotes":""},"categories":[27,75],"tags":[117,3785,507,126,3513],"class_list":["post-8011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-critique","category-jeux-video","tag-jeux-video","tag-naughty-dog","tag-playstation","tag-ps4","tag-the-last-of-us-part-ii"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/8011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/comments?post=8011"}],"version-history":[{"count":3,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/8011\/revisions"}],"predecessor-version":[{"id":8077,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/posts\/8011\/revisions\/8077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/media\/8076"}],"wp:attachment":[{"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/media?parent=8011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/categories?post=8011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cine-techno.com\/wp\/wp-json\/wp\/v2\/tags?post=8011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}